{"id":7620,"date":"2024-10-19T10:53:45","date_gmt":"2024-10-19T13:53:45","guid":{"rendered":"https:\/\/www.uplayamerica.com\/?post_type=product&#038;p=7620"},"modified":"2026-08-14T12:51:41","modified_gmt":"2026-08-14T15:51:41","slug":"hammer","status":"publish","type":"product","link":"https:\/\/www.uplayamerica.com\/es\/producto\/hammer\/","title":{"rendered":"Hammer"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row el_id=\u00bbdescripcionlarga\u00bb conditional_render=\u00bb%5B%7B%22value_role%22%3A%22administrator%22%7D%5D\u00bb css_params=\u00bb\u00bb css=\u00bb.vc_custom_1762966621302{padding-top: 30px !important;padding-bottom: 30px !important;}\u00bb][vc_column][vc_column_text css=\u00bb\u00bb css_params=\u00bb\u00bb]<\/p>\n<p style=\"text-align: center;\"><div class=\"porto-block\" data-id=\"8791\"><style>.vc_custom_1762812936930{border-top-width: 2px !important;padding-top: 30px !important;padding-bottom: 30px !important;border-top-style: solid !important;border-color: var(--porto-primary-color) !important;}.vc_custom_1768571572259{margin-top: 0px !important;padding-top: 0px !important;}.vc_custom_1772129172817{margin-top: 0px !important;padding-top: 30px !important;padding-bottom: 30px !important;}.vc_custom_1762964565600{padding-right: 5% !important;padding-left: 5% !important;}.vc_custom_1763401623402{margin-top: 0px !important;padding-top: 0px !important;}.vc_custom_1762965927043{margin-bottom: 0px !important;padding-top: 30px !important;padding-bottom: 0px !important;}.vc_custom_1768571579348{margin-top: 0px !important;padding-top: 10px !important;}.vc_custom_1763665981507{border-top-width: 2px !important;border-right-width: 2px !important;border-bottom-width: 2px !important;border-left-width: 2px !important;padding-top: 10px !important;padding-right: 20px !important;padding-bottom: 10px !important;padding-left: 20px !important;border-left-style: solid !important;border-right-style: solid !important;border-top-style: solid !important;border-bottom-style: solid !important;border-color: var(--porto-primary-color) !important;}@media(max-width:767px){.vc_custom_1762964293415{padding-top:30px!important;padding-bottom:30px!important;}}@media(max-width:767px){.vc_custom_1768571579348{padding-bottom:30px!important;}}<\/style>[vc_row el_id=\"descripcionlarga\" conditional_render=\"%5B%7B%22value_role%22%3A%22administrator%22%7D%5D\" css_params=\"\" css=\".vc_custom_1762812936930{border-top-width: 2px !important;padding-top: 30px !important;padding-bottom: 30px !important;border-top-style: solid !important;border-color: var(--porto-primary-color) !important;}\"][vc_column][vc_column_text css=\"\" css_params=\"\"]<\/p>\r\n<h2 style=\"text-align: center;\">Completa el formulario para solicitar tu cotizaci\u00f3n<\/h2>\r\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row conditional_render=\"%5B%7B%22value_role%22%3A%22administrator%22%7D%5D\" css_params=\"\" css=\".vc_custom_1768571572259{margin-top: 0px !important;padding-top: 0px !important;}\" el_class=\"invertir-mobile\"][vc_column width=\"1\/2\" conditional_render=\"%5B%7B%22value_role%22%3A%22administrator%22%7D%5D\" css_params=\"\" el_class=\"tabsproducto\"][vc_tabs position=\"top-justify\" skin=\"dark\" interval=\"3\"][vc_tab show_icon=\"yes\" title=\"FAQ para Distribuidores<br \/>\r\n&amp; Operadores\" tab_id=\"1574000295454-0-4\"]<div class=\"porto-ultimate-content-box-container \"><div class=\"porto-ultimate-content-box porto_ucb_e35a9346cd70594d63c013acc42ebe9d\" style=\"\">[vc_tta_accordion title_tag=\"h3\" style=\"modern\" spacing=\"5\" c_icon=\"\" active_section=\"\" no_fill=\"true\" collapsible_all=\"true\" css_params=\"\" css=\".vc_custom_1763401623402{margin-top: 0px !important;padding-top: 0px !important;}\"][vc_tta_section title=\"1. \u00bfQu\u00e9 es una m\u00e1quina de boxeo arcade?\" tab_id=\"1762881898590-c8db1e33-f2e2\"][vc_column_text css=\"\" css_params=\"\"]Una m\u00e1quina de boxeo arcade es un juego de golpeo operado con monedas que mide la fuerza del pu\u00f1etazo del jugador. Es una atracci\u00f3n muy popular en bares, salones de juegos y eventos porque llama la atenci\u00f3n y genera ingresos constantes.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"2. \u00bfLas m\u00e1quinas son nuevas o reacondicionadas?\" tab_id=\"1762881898597-1dd0445a-a3dc\"][vc_column_text css=\"\" css_params=\"\"]Todas nuestras m\u00e1quinas de boxeo son completamente nuevas y provienen directamente de nuestros centros de distribuci\u00f3n en Florida (EE. UU.) y Polonia.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"3. \u00bfPuedo personalizar la m\u00e1quina con mi logo o colores?\" tab_id=\"1762885798734-abdaf57c-dcda\"][vc_column_text css=\"\" css_params=\"\"]<\/p>\r\n<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto [content-visibility:auto] supports-[content-visibility:auto]:[contain-intrinsic-size:auto_100lvh] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-WEB:6bc8d363-ba99-4a1f-b4bd-e6fa77996314-11\" data-testid=\"conversation-turn-24\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\r\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] thread-sm:[--thread-content-margin:--spacing(6)] thread-lg:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\r\n<div class=\"[--thread-content-max-width:40rem] thread-lg:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\r\n<div class=\"flex max-w-full flex-col grow\">\r\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"306272a4-205a-4c8f-88e6-3a2fa0b251b9\" data-message-model-slug=\"gpt-5-1\">\r\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\r\n<div class=\"markdown prose dark:prose-invert w-full break-words light markdown-new-styling\">\r\n<p data-start=\"0\" data-end=\"179\" data-is-last-node=\"\" data-is-only-node=\"\">S\u00ed. Ofrecemos personalizaci\u00f3n completa de marca \u2014 incluyendo dise\u00f1os en vinilo, logos y esquemas de colores LED \u2014 para que coincida con tu marca o el estilo de tu establecimiento.<\/p>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/article>\r\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"4. \u00bfCu\u00e1l es el precio de una m\u00e1quina de boxeo?\" tab_id=\"1762885824267-d76b15a1-d4ae\"][vc_column_text css=\"\" css_params=\"\"]Los precios var\u00edan seg\u00fan el modelo, la cantidad y la personalizaci\u00f3n. Cont\u00e1ctanos para solicitar una cotizaci\u00f3n: ofrecemos precios para distribuidores, operadores y clientes, con presupuestos sin compromiso.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"5. \u00bfRealizan env\u00edos internacionales?\" tab_id=\"1762885846917-4d597feb-18e9\"][vc_column_text css=\"\" css_params=\"\"]S\u00ed, enviamos a <strong data-start=\"53\" data-end=\"129\">Estados Unidos, Canad\u00e1, M\u00e9xico, Bolivia, Argentina, Colombia, Per\u00fa y m\u00e1s<\/strong>, directamente desde Florida y Polonia. Nos encargamos de la log\u00edstica y podemos entregar <strong data-start=\"219\" data-end=\"238\">puerta a puerta<\/strong>. \u00a1A toda Am\u00e9rica![\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"6. \u00bfCu\u00e1nto tarda la entrega?\" tab_id=\"1762885867004-e072aad9-4047\"][vc_column_text css=\"\" css_params=\"\"]El tiempo de entrega depende de tu ubicaci\u00f3n y de la disponibilidad de stock. En Estados Unidos, la entrega suele demorar entre 2 y 5 d\u00edas h\u00e1biles. Los env\u00edos internacionales var\u00edan entre 3 y 6 semanas.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"7. \u00bfQu\u00e9 m\u00e9todos de pago aceptan?\" tab_id=\"1762885884850-a25f3ef8-41b1\"][vc_column_text css=\"\" css_params=\"\"]Aceptamos transferencias bancarias, tarjetas de cr\u00e9dito, ACH, cheque y efectivo. Un dep\u00f3sito del 50% confirma tu pedido y el saldo se abona antes del env\u00edo.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"8. \u00bfCu\u00e1l es el per\u00edodo de garant\u00eda?\" tab_id=\"1762885909084-65bd0095-2a48\"][vc_column_text css=\"\" css_params=\"\"]<\/p>\r\n<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto [content-visibility:auto] supports-[content-visibility:auto]:[contain-intrinsic-size:auto_100lvh] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-WEB:6bc8d363-ba99-4a1f-b4bd-e6fa77996314-22\" data-testid=\"conversation-turn-46\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\r\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] thread-sm:[--thread-content-margin:--spacing(6)] thread-lg:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\r\n<div class=\"[--thread-content-max-width:40rem] thread-lg:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\r\n<div class=\"flex max-w-full flex-col grow\">\r\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"4b84006f-eed2-4a63-9a5c-84d5686ed93a\" data-message-model-slug=\"gpt-5-1\">\r\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\r\n<div class=\"markdown prose dark:prose-invert w-full break-words light markdown-new-styling\">\r\n<p data-start=\"38\" data-end=\"187\" data-is-last-node=\"\" data-is-only-node=\"\">Nuestras m\u00e1quinas incluyen una <strong>garant\u00eda de 3 a\u00f1os<\/strong> en todas las partes el\u00e9ctricas y defectos de fabricaci\u00f3n. Tambi\u00e9n brindamos soporte t\u00e9cnico remoto.<\/p>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/article>\r\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"9. \u00bfProporcionan repuestos?\" tab_id=\"1762885930452-8b15f005-ea5e\"][vc_column_text css=\"\" css_params=\"\"]S\u00ed \u2014 contamos con todas las piezas principales (bolsas de golpe, c\u00e1maras internas, sensores, fuentes de poder, pantallas, etc.) y enviamos directamente desde nuestro almac\u00e9n en Florida.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"10. \u00bfQu\u00e9 tan f\u00e1cil es la instalaci\u00f3n?\" tab_id=\"1762885948908-09e0e807-72bf\"][vc_column_text css=\"\" css_params=\"\"]La instalaci\u00f3n es sencilla. La m\u00e1quina llega casi completamente ensamblada \u2014 solo ten\u00e9s que enchufarla, colocar la tapa superior y estar\u00e1 lista para jugar. No se requieren herramientas ni habilidades especiales.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"11. \u00bfQui\u00e9nes son nuestros clientes ideales?\" tab_id=\"1762885969143-28799315-5d04\"][vc_column_text css=\"\" css_params=\"\"]Nuestros mejores socios son <strong>bares, discotecas, boliches, pistas de bowling, centros deportivos, parques de diversiones, centros de entretenimiento familiar y lugares de eventos<\/strong> con alto tr\u00e1fico de clientes. Las ubicaciones donde la gente pasa tiempo socializando y compitiendo funcionan excepcionalmente bien.[\/vc_column_text][\/vc_tta_section][\/vc_tta_accordion]<\/div><\/div>[\/vc_tab][vc_tab title=\"FAQ para<br \/>\r\nClientes\" tab_id=\"1574000295599-0-1\"]<div class=\"porto-ultimate-content-box-container \"><div class=\"porto-ultimate-content-box porto_ucb_e35a9346cd70594d63c013acc42ebe9d\" style=\"\">[vc_tta_accordion title_tag=\"h3\" style=\"modern\" spacing=\"5\" c_icon=\"\" active_section=\"\" no_fill=\"true\" collapsible_all=\"true\" css_params=\"\"][vc_tta_section title=\"1. \u00bfPuedo alquilar una m\u00e1quina para una fiesta o evento corporativo?\" tab_id=\"1762886966391-3c74630b-ba67\"][vc_column_text css=\"\" css_params=\"\"]\u00a1Por supuesto! Nuestras m\u00e1quinas de boxeo son las favoritas en cumplea\u00f1os, festivales, ferias, carnavales y eventos corporativos (solo en Florida).[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"2. \u00bfC\u00f3mo funcionan los alquileres?\" tab_id=\"1762886966405-16117b2d-6111\"][vc_column_text css=\"\" css_params=\"\"]Entregamos, instalamos y retiramos la m\u00e1quina despu\u00e9s de tu evento, o tambi\u00e9n pod\u00e9s dejarla en nuestro almac\u00e9n. Solo eleg\u00eds la fecha, el lugar y la duraci\u00f3n \u2014 nosotros nos encargamos del resto.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"3. \u00bfEs f\u00e1cil de mover?\" tab_id=\"1762887035489-2c813a00-3850\"][vc_column_text css=\"\" css_params=\"\"]<\/p>\r\n<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto [content-visibility:auto] supports-[content-visibility:auto]:[contain-intrinsic-size:auto_100lvh] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-WEB:6bc8d363-ba99-4a1f-b4bd-e6fa77996314-34\" data-testid=\"conversation-turn-70\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\r\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] thread-sm:[--thread-content-margin:--spacing(6)] thread-lg:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\r\n<div class=\"[--thread-content-max-width:40rem] thread-lg:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\r\n<div class=\"flex max-w-full flex-col grow\">\r\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"6195195a-88f2-4bd8-b002-82d5126a10d2\" data-message-model-slug=\"gpt-5-mini\">\r\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\r\n<div class=\"markdown prose dark:prose-invert w-full break-words light markdown-new-styling\">\r\n<p data-start=\"0\" data-end=\"163\" data-is-last-node=\"\" data-is-only-node=\"\">La m\u00e1quina es pesada, pero est\u00e1 montada sobre ruedas para un transporte m\u00e1s f\u00e1cil. Nuestro equipo se encarga de la entrega e instalaci\u00f3n por seguridad y comodidad.<\/p>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/article>\r\n<p>[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"4. \u00bfSe puede usar al aire libre?\" tab_id=\"1762887057188-fc84e8a3-a88a\"][vc_column_text css=\"\" css_params=\"\"]S\u00ed, la m\u00e1quina se puede usar al aire libre bajo un \u00e1rea cubierta para protegerla de la lluvia o la luz solar directa. Es resistente al agua y actualmente se utiliza en carnavales durante todo el a\u00f1o.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"5. \u00bfQu\u00e9 tipo de fuente de alimentaci\u00f3n utiliza?\" tab_id=\"1762887076563-9fbe2b04-ccd3\"][vc_column_text css=\"\" css_params=\"\"]Utiliza un enchufe est\u00e1ndar de 110\u202fV, pero se puede personalizar para otros pa\u00edses de Latinoam\u00e9rica a 220\u202fV. Solo hay que conectarla \u2014 no se necesitan conexiones especiales.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"6. \u00bfCu\u00e1ntas personas pueden jugar?\" tab_id=\"1762887094875-0d77700e-31f1\"][vc_column_text css=\"\" css_params=\"\"]Algunas m\u00e1quinas est\u00e1n dise\u00f1adas para un solo jugador, mientras que otras, como la Boxer Fist, permiten varios usuarios (hasta 3 jugadores). Perfectas para competencias grupales entre amigos.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"7. \u00bfOfrecen personal o asistentes en el lugar?\" tab_id=\"1762887113406-a8d1485a-d45c\"][vc_column_text css=\"\" css_params=\"\"]S\u00ed, para eventos grandes o festivales, podemos proporcionar un asistente que supervise la m\u00e1quina y ayude a los jugadores (solo en Florida).[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"8. \u00bfQu\u00e9 sucede si la m\u00e1quina deja de funcionar durante un evento?\" tab_id=\"1762887131922-a119b203-b5df\"][vc_column_text css=\"\" css_params=\"\"]Nuestro equipo est\u00e1 disponible los 7 d\u00edas de la semana. Brindamos soporte remoto inmediato o, si es necesario, una unidad de reemplazo.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"9. \u00bfRequieren un dep\u00f3sito de seguridad?\" tab_id=\"1762887151503-2097d5d4-b7b2\"][vc_column_text css=\"\" css_params=\"\"]S\u00ed, para los alquileres requerimos un dep\u00f3sito reembolsable, que se devuelve una vez que la m\u00e1quina se recoge en buen estado.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"10. \u00bfC\u00f3mo hago para reservar?\" tab_id=\"1762887169080-c172cbc4-b0ab\"][vc_column_text css=\"\" css_params=\"\"]Simplemente cont\u00e1ctanos con los detalles de tu evento (fecha, lugar y duraci\u00f3n), y te enviaremos una cotizaci\u00f3n y la confirmaci\u00f3n de disponibilidad.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\"11. \u00bfEs una buena idea comprar una m\u00e1quina de boxeo para un Airbnb o alquileres vacacionales?\" tab_id=\"1762887187690-3031b84b-2c83\"][vc_column_text css=\"\" css_params=\"\"]<\/p>\r\n<p data-start=\"0\" data-end=\"306\">\u00a1S\u00ed! Una m\u00e1quina de boxeo puede ser una excelente inversi\u00f3n para propietarios de Airbnb o alquileres vacacionales que quieran destacarse y ofrecer a los hu\u00e9spedes una experiencia divertida y memorable. Muchos anfitriones informan mejores rese\u00f1as y mayores tasas de reserva despu\u00e9s de agregar juegos arcade.<\/p>\r\n<p data-start=\"308\" data-end=\"328\">\u2705 M\u00e1s adecuado para:<\/p>\r\n<ul data-start=\"330\" data-end=\"519\">\r\n<li data-start=\"330\" data-end=\"385\">\r\n<p data-start=\"332\" data-end=\"385\">Propiedades que reciben grupos, familias o eventos.<\/p>\r\n<\/li>\r\n<li data-start=\"330\" data-end=\"385\">\r\n<p data-start=\"332\" data-end=\"385\">Alojamientos con \u00e1reas dedicadas a la recreaci\u00f3n o juegos.<\/p>\r\n<\/li>\r\n<li data-start=\"449\" data-end=\"519\">\r\n<p data-start=\"451\" data-end=\"519\">Anfitriones que quieran ofrecer algo \u00fanico y llamativo en las fotos.<\/p>\r\n<\/li>\r\n<\/ul>\r\n<p data-start=\"521\" data-end=\"705\" data-is-last-node=\"\" data-is-only-node=\"\">\ud83d\udca1 Consejo: La m\u00e1quina se puede configurar en modo de juego libre o programar para aceptar billetes, monedas, fichas o tarjetas, lo que te permite controlar c\u00f3mo la usan los hu\u00e9spedes.<\/p>\r\n<p>[\/vc_column_text][\/vc_tta_section][\/vc_tta_accordion]<\/div><\/div>[\/vc_tab][\/vc_tabs][\/vc_column][vc_column width=\"1\/2\" conditional_render=\"%5B%7B%22value_role%22%3A%22administrator%22%7D%5D\" css_params=\"\" el_class=\"formproductos\" custom_css_response=\"@media(max-width:767px){.vc_custom_1762964293415{padding-top:30px!important;padding-bottom:30px!important;}}\" css=\".vc_custom_1762964565600{padding-right: 5% !important;padding-left: 5% !important;}\"]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f8792-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"8792\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/product\/7620#wpcf7-f8792-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"8792\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f8792-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.7\" \/>\n<\/fieldset>\n<div class=\"row formcontacto\">\n  <div class=\"col-lg-12\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre completo (*)\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/div>\n  <div class=\"col-lg-12\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email (*)\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/div>\n  <div class=\"col-lg-12\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span><\/div>\n  <div class=\"col-lg-12\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-country\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Pa\u00eds (*)\" value=\"\" type=\"text\" name=\"your-country\" \/><\/span><\/div>\n    <div class=\"col-lg-12\">\n    <p style=\"margin-bottom:5px\"><strong>Selecciona tu tipo de usuario<\/strong><\/p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-role\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-role\"><option value=\"Distribuidor\">Distribuidor<\/option><option value=\"Operador\">Operador<\/option><option value=\"Cliente\">Cliente<\/option><option value=\"Otro\">Otro<\/option><\/select><\/span>\n  <\/div>\n  <div class=\"col-lg-12\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"2\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Mensaje\" name=\"your-message\"><\/textarea><\/span><\/div>\n  <span class=\"wpcf7-form-control-wrap producto-titulo\" data-name=\"producto-titulo\"><input type=\"hidden\" name=\"producto-titulo\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\"><\/span>\n  <div class=\"col-lg-12\"><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-default\" type=\"submit\" value=\"ENVIAR SOLICITUD\" \/><\/div>\n<\/div>\n\n<style type=\"text\/css\">\n.formcontacto input[type=\"email\"],\n.formcontacto input[type=\"text\"],\n.formcontacto textarea, \n.formcontacto  select{\n  border-color: #7b858a !important;\n  margin-bottom: 15px !important;\n  width: 100%;\n  padding: 8px;\n}\n\n\n\/* Estilo acorde\u00f3n *\/\n.checkbox-accordion {\n  border: 1px solid #7b858a;\n  margin-bottom: 10px !important;\n}\n\n.accordion-toggle {\n  background-color: #fff;color: #777;\n  border: none;\n  width: 100%;\n  text-align: left;\n  padding: 10px;\n  font-weight: 400;\n  cursor: pointer;\n  transition: background-color 0.2s;\n}\n\n.accordion-toggle:hover {\n  background-color: #eaeaea;\n}\n\n.checkbox-content {\n  display: none;\n  padding: 10px;\n  border-top: 1px solid #7b858a;\n}\n\n.checkbox-content span.wpcf7-list-item {\n  display: block;\n  margin-bottom: 5px;\n}\n\n.checkbox-content input[type=\"checkbox\"] {\n  margin-right: 8px;\n  accent-color: #cd1542;\n}\n\n\/* Estados del formulario *\/\n.wpcf7 form.sent .wpcf7-response-output {\n  border: 2px solid #74a322 !important;\n  padding: 10px;\n  margin: 15px 0px;\n}\n\n.wpcf7 form.invalid .wpcf7-response-output {\n  border-color: #f6914d;\n  margin: 15px 0px;\n}\n\n[type=\"submit\"]:not(:disabled) {\n  background-color: #cd1542 !important;\n  color: #fff;margin-top:30px !important;\n  border: none;\n  padding: 10px 20px;\n  cursor: pointer;\n}\n<\/style>\n\n<script>\ndocument.addEventListener('DOMContentLoaded', function() {\n  const toggle = document.querySelector('.accordion-toggle');\n  const content = document.querySelector('.checkbox-content');\n\n  toggle.addEventListener('click', function() {\n    content.style.display = content.style.display === 'block' ? 'none' : 'block';\n    toggle.textContent = content.style.display === 'block'\n      ? 'Select parts \u25b2'\n      : 'Select parts \u25bc';\n  });\n});\n<\/script><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[vc_icon icon_fontawesome=\"fas fa-video\" color=\"custom\" align=\"center\" css=\".vc_custom_1762965927043{margin-bottom: 0px !important;padding-top: 30px !important;padding-bottom: 0px !important;}\" custom_color=\"#cd1542\" css_params=\"\"][vc_column_text css=\".vc_custom_1768571579348{margin-top: 0px !important;padding-top: 10px !important;}\" css_params=\"{``css_padding_bottom_md``:``30px``}\" custom_css_response=\"@media(max-width:767px){.vc_custom_1768571579348{padding-bottom:30px!important;}}\"]<\/p>\r\n<h3 style=\"text-align: center;\">Estamos trabajando en nuevos videos<\/h3>\r\n<h2 style=\"text-align: center;\"><span style=\"color: #cd1542;\">\u00a1Pr\u00f3ximamente!<\/span><\/h2>\r\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row wrap_container=\"yes\" conditional_render=\"%5B%7B%22value_role%22%3A%22administrator%22%7D%5D\" css_params=\"\" css=\".vc_custom_1772129172817{margin-top: 0px !important;padding-top: 30px !important;padding-bottom: 30px !important;}\"][vc_column][vc_column_text css=\".vc_custom_1763665981507{border-top-width: 2px !important;border-right-width: 2px !important;border-bottom-width: 2px !important;border-left-width: 2px !important;padding-top: 10px !important;padding-right: 20px !important;padding-bottom: 10px !important;padding-left: 20px !important;border-left-style: solid !important;border-right-style: solid !important;border-top-style: solid !important;border-bottom-style: solid !important;border-color: var(--porto-primary-color) !important;}\" css_params=\"\"]<\/p>\r\n<h3 style=\"text-align: center;\">Calidad europea \u2013 \"Dise\u00f1ada y fabricada con orgullo en Polonia\"<\/h3>\r\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7278\" src=\"https:\/\/www.uplayamerica.com\/wp-content\/uploads\/2024\/10\/Sin-titulo1-6.jpg\" alt=\"\" width=\"330\" height=\"37\" \/><\/p>\n<h2 style=\"text-align: left; margin-bottom: 0px; margin-top: 0px; padding-top: 0px; line-height: 20px;\"><span style=\"color: #cd1542;\"><strong>HAMMER<\/strong><\/span><\/h2>\n<p class=\"contact-text\"><a href=\"#descripcionlarga\">Contactanos!<\/a><\/p>\n<p>Es un cl\u00e1sico juego de prueba de fuerza que desaf\u00eda a los jugadores a golpear con toda su potencia. Perfecto para parques de diversiones, arcades y centros de entretenimiento familiar (FEC), este juego atemporal es divertido, competitivo y atrae a multitudes con sus luces LED vibrantes.<\/p>\n<p><span style=\"color: #cd1542;\"><strong>CARACTER\u00cdSTICAS DE FUERZA<\/strong>:<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\"><strong>Desaf\u00edo de golpe de potencia<\/strong>: Gira el martillo y ve qu\u00e9 tan alto puedes llegar en la puntuaci\u00f3n.<\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>Luces LED brillantes<\/strong>: Luces llamativas que aumentan la emoci\u00f3n y atraen la atenci\u00f3n.<\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>Opci\u00f3n de tickets<\/strong>: Se puede configurar para premiar con boletos, lo que lo hace ideal para lugares de canje.<\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>Dificultad ajustable y modo de juego libre<\/strong>: Adecuado para jugadores de todas las edades y niveles de habilidad.<\/span><\/li>\n<li><span style=\"color: #000000;\"><strong>Opciones de pago flexibles<\/strong>: Soporta m\u00faltiples tipos de pago, incluyendo billetes, monedas, tarjetas y fichas, lo que la hace adaptable a cualquier moneda.<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #cd1542;\"><strong>ACTUALIZACIONES DISPONIBLES<\/strong>:<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Aceptador de billetes.<\/span><\/li>\n<li><span style=\"color: #000000;\">Mecanismo de aceptaci\u00f3n de monedas.<\/span><\/li>\n<li><span style=\"color: #000000;\">Cable de alimentaci\u00f3n de 4 metros.<\/span><\/li>\n<li><span style=\"color: #000000;\">Pegatinas personalizadas y branding.<\/span><\/li>\n<li><span style=\"color: #000000;\">Billetes, monedas, fichas, tickets, tarjetas de cr\u00e9dito, lectores de tarjetas.<\/span><\/li>\n<li><span style=\"color: #000000;\">Se adapta a diferentes monedas.<\/span><\/li>\n<\/ul>\n<div class=\"dimensions\"><strong><span style=\"color: #cd1542;\">DIMENSIONES:<\/span><\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7169\" src=\"https:\/\/www.uplayamerica.com\/wp-content\/uploads\/2024\/11\/AZ-removebg-preview.png\" alt=\"\" width=\"20\" height=\"20\" \/><span style=\"color: #163b81;\"><strong> Alto:<\/strong> <\/span><span style=\"color: #000000;\">\u00a0225 Cm \/ 89&#8243;<\/span>\u00a0 \u00a0 \u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7171\" src=\"https:\/\/www.uplayamerica.com\/wp-content\/uploads\/2024\/11\/roj-removebg-preview.png\" alt=\"\" width=\"20\" height=\"20\" \/> <span style=\"color: #cd1542;\"><strong>Ancho:<\/strong><\/span><span style=\"color: #000000;\"> 95 cm \/ 38&#8243;<\/span><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7173\" src=\"https:\/\/www.uplayamerica.com\/wp-content\/uploads\/2024\/11\/am-removebg-preview.png\" alt=\"\" width=\"20\" height=\"20\" \/><span style=\"color: #ffb24b;\"><strong> Largo:<\/strong><\/span> <span style=\"color: #000000;\">140 cm \/ 56&#8243;<\/span>\u00a0 \u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7175\" src=\"https:\/\/www.uplayamerica.com\/wp-content\/uploads\/2024\/11\/we-removebg-preview.png\" alt=\"\" width=\"25\" height=\"25\" \/> <span style=\"color: #000000;\"><strong>Peso:<\/strong> 125 kg \/ 276 lbs<\/span><\/div>\n<div class=\"dimensions\">\n<p><strong><span style=\"color: #cd1542;\">DIMENSIONES PALETIZADAS:<\/span><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7169\" src=\"https:\/\/www.uplayamerica.com\/wp-content\/uploads\/2024\/11\/AZ-removebg-preview.png\" alt=\"\" width=\"20\" height=\"20\" \/><span style=\"color: #163b81;\"><strong> Alto:<\/strong> <\/span><span style=\"color: #000000;\">236 cm \/ 93&#8243;<\/span>\u00a0 \u00a0 \u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7171\" src=\"https:\/\/www.uplayamerica.com\/wp-content\/uploads\/2024\/11\/roj-removebg-preview.png\" alt=\"\" width=\"20\" height=\"20\" \/> <span style=\"color: #cd1542;\"><strong>Ancho:<\/strong> <\/span><span style=\"color: #000000;\">104 cm \/ 41&#8243;<\/span><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7173\" src=\"https:\/\/www.uplayamerica.com\/wp-content\/uploads\/2024\/11\/am-removebg-preview.png\" alt=\"\" width=\"20\" height=\"20\" \/><span style=\"color: #ffb24b;\"><strong> Largo:<\/strong><\/span> <span style=\"color: #000000;\">157 cm \/ 62&#8243;<\/span>\u00a0 \u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7175\" src=\"https:\/\/www.uplayamerica.com\/wp-content\/uploads\/2024\/11\/we-removebg-preview.png\" alt=\"\" width=\"25\" height=\"25\" \/> <span style=\"color: #000000;\"><strong>Peso:<\/strong> 144 kg \/ 316 lbs<\/span><\/p>\n<\/div>\n","protected":false},"featured_media":9901,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[121],"product_tag":[],"class_list":["post-7620","product","type-product","status-publish","has-post-thumbnail","product_cat-hammer-es","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hammer - Uplay America<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uplayamerica.com\/es\/producto\/hammer\/\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hammer\" \/>\n<meta property=\"og:description\" content=\"HAMMER Contactanos! Es un cl\u00e1sico juego de prueba de fuerza que desaf\u00eda a los jugadores a golpear con toda su potencia. Perfecto para parques de diversiones, arcades y centros de entretenimiento familiar (FEC), este juego atemporal es divertido, competitivo y atrae a multitudes con sus luces LED vibrantes.  CARACTER\u00cdSTICAS DE FUERZA:   Desaf\u00edo de golpe de potencia: Gira el martillo y ve qu\u00e9 tan alto puedes llegar en la puntuaci\u00f3n.  Luces LED brillantes: Luces llamativas que aumentan la emoci\u00f3n y atraen la atenci\u00f3n.  Opci\u00f3n de tickets: Se puede configurar para premiar con boletos, lo que lo hace ideal para lugares de canje.  Dificultad ajustable y modo de juego libre: Adecuado para jugadores de todas las edades y niveles de habilidad.  Opciones de pago flexibles: Soporta m\u00faltiples tipos de pago, incluyendo billetes, monedas, tarjetas y fichas, lo que la hace adaptable a cualquier moneda.  ACTUALIZACIONES DISPONIBLES:   Aceptador de billetes.  Mecanismo de aceptaci\u00f3n de monedas.  Cable de alimentaci\u00f3n de 4 metros.  Pegatinas personalizadas y branding.  Billetes, monedas, fichas, tickets, tarjetas de cr\u00e9dito, lectores de tarjetas.  Se adapta a diferentes monedas.  DIMENSIONES:  Alto: \u00a0225 Cm \/ 89&quot;\u00a0 \u00a0 \u00a0 Ancho: 95 cm \/ 38&quot;  Largo: 140 cm \/ 56&quot;\u00a0 \u00a0 \u00a0 Peso: 125 kg \/ 276 lbs   DIMENSIONES PALETIZADAS:   Alto: 236 cm \/ 93&quot;\u00a0 \u00a0 \u00a0 Ancho: 104 cm \/ 41&quot;  Largo: 157 cm \/ 62&quot;\u00a0 \u00a0 \u00a0 Peso: 144 kg \/ 316 lbs\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uplayamerica.com\/es\/producto\/hammer\/\" \/>\n<meta property=\"og:site_name\" content=\"Uplay America\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UPlayAmerica\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-14T15:51:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uplayamerica.com\/wp-content\/uploads\/2024\/10\/esp-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"1016\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uplayamerica.com\\\/es\\\/producto\\\/hammer\\\/\",\"url\":\"https:\\\/\\\/www.uplayamerica.com\\\/es\\\/producto\\\/hammer\\\/\",\"name\":\"Hammer - Uplay America\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uplayamerica.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uplayamerica.com\\\/es\\\/producto\\\/hammer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uplayamerica.com\\\/es\\\/producto\\\/hammer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.uplayamerica.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/esp-1.webp\",\"datePublished\":\"2024-10-19T13:53:45+00:00\",\"dateModified\":\"2026-08-14T15:51:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uplayamerica.com\\\/es\\\/producto\\\/hammer\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uplayamerica.com\\\/es\\\/producto\\\/hammer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.uplayamerica.com\\\/es\\\/producto\\\/hammer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.uplayamerica.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/esp-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.uplayamerica.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/esp-1.webp\",\"width\":500,\"height\":1016},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uplayamerica.com\\\/es\\\/producto\\\/hammer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.uplayamerica.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.uplayamerica.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hammer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uplayamerica.com\\\/#website\",\"url\":\"https:\\\/\\\/www.uplayamerica.com\\\/\",\"name\":\"Uplay America\",\"description\":\"Bocher Machines\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.uplayamerica.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uplayamerica.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.uplayamerica.com\\\/#organization\",\"name\":\"Uplay America\",\"url\":\"https:\\\/\\\/www.uplayamerica.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.uplayamerica.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.uplayamerica.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/logo-boxer-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.uplayamerica.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/logo-boxer-1.webp\",\"width\":200,\"height\":114,\"caption\":\"Uplay America\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uplayamerica.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UPlayAmerica\",\"https:\\\/\\\/www.instagram.com\\\/uplayamerica\",\"https:\\\/\\\/www.youtube.com\\\/@uplayamericaboxermachines\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hammer - Uplay America","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uplayamerica.com\/es\/producto\/hammer\/","og_type":"article","og_title":"Hammer","og_description":"HAMMER Contactanos! Es un cl\u00e1sico juego de prueba de fuerza que desaf\u00eda a los jugadores a golpear con toda su potencia. Perfecto para parques de diversiones, arcades y centros de entretenimiento familiar (FEC), este juego atemporal es divertido, competitivo y atrae a multitudes con sus luces LED vibrantes.  CARACTER\u00cdSTICAS DE FUERZA:   Desaf\u00edo de golpe de potencia: Gira el martillo y ve qu\u00e9 tan alto puedes llegar en la puntuaci\u00f3n.  Luces LED brillantes: Luces llamativas que aumentan la emoci\u00f3n y atraen la atenci\u00f3n.  Opci\u00f3n de tickets: Se puede configurar para premiar con boletos, lo que lo hace ideal para lugares de canje.  Dificultad ajustable y modo de juego libre: Adecuado para jugadores de todas las edades y niveles de habilidad.  Opciones de pago flexibles: Soporta m\u00faltiples tipos de pago, incluyendo billetes, monedas, tarjetas y fichas, lo que la hace adaptable a cualquier moneda.  ACTUALIZACIONES DISPONIBLES:   Aceptador de billetes.  Mecanismo de aceptaci\u00f3n de monedas.  Cable de alimentaci\u00f3n de 4 metros.  Pegatinas personalizadas y branding.  Billetes, monedas, fichas, tickets, tarjetas de cr\u00e9dito, lectores de tarjetas.  Se adapta a diferentes monedas.  DIMENSIONES:  Alto: \u00a0225 Cm \/ 89\"\u00a0 \u00a0 \u00a0 Ancho: 95 cm \/ 38\"  Largo: 140 cm \/ 56\"\u00a0 \u00a0 \u00a0 Peso: 125 kg \/ 276 lbs   DIMENSIONES PALETIZADAS:   Alto: 236 cm \/ 93\"\u00a0 \u00a0 \u00a0 Ancho: 104 cm \/ 41\"  Largo: 157 cm \/ 62\"\u00a0 \u00a0 \u00a0 Peso: 144 kg \/ 316 lbs","og_url":"https:\/\/www.uplayamerica.com\/es\/producto\/hammer\/","og_site_name":"Uplay America","article_publisher":"https:\/\/www.facebook.com\/UPlayAmerica","article_modified_time":"2026-08-14T15:51:41+00:00","og_image":[{"width":500,"height":1016,"url":"https:\/\/www.uplayamerica.com\/wp-content\/uploads\/2024\/10\/esp-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uplayamerica.com\/es\/producto\/hammer\/","url":"https:\/\/www.uplayamerica.com\/es\/producto\/hammer\/","name":"Hammer - Uplay America","isPartOf":{"@id":"https:\/\/www.uplayamerica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uplayamerica.com\/es\/producto\/hammer\/#primaryimage"},"image":{"@id":"https:\/\/www.uplayamerica.com\/es\/producto\/hammer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uplayamerica.com\/wp-content\/uploads\/2024\/10\/esp-1.webp","datePublished":"2024-10-19T13:53:45+00:00","dateModified":"2026-08-14T15:51:41+00:00","breadcrumb":{"@id":"https:\/\/www.uplayamerica.com\/es\/producto\/hammer\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uplayamerica.com\/es\/producto\/hammer\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uplayamerica.com\/es\/producto\/hammer\/#primaryimage","url":"https:\/\/www.uplayamerica.com\/wp-content\/uploads\/2024\/10\/esp-1.webp","contentUrl":"https:\/\/www.uplayamerica.com\/wp-content\/uploads\/2024\/10\/esp-1.webp","width":500,"height":1016},{"@type":"BreadcrumbList","@id":"https:\/\/www.uplayamerica.com\/es\/producto\/hammer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uplayamerica.com\/es\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.uplayamerica.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Hammer"}]},{"@type":"WebSite","@id":"https:\/\/www.uplayamerica.com\/#website","url":"https:\/\/www.uplayamerica.com\/","name":"Uplay America","description":"Bocher Machines","publisher":{"@id":"https:\/\/www.uplayamerica.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uplayamerica.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.uplayamerica.com\/#organization","name":"Uplay America","url":"https:\/\/www.uplayamerica.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uplayamerica.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.uplayamerica.com\/wp-content\/uploads\/2020\/08\/logo-boxer-1.webp","contentUrl":"https:\/\/www.uplayamerica.com\/wp-content\/uploads\/2020\/08\/logo-boxer-1.webp","width":200,"height":114,"caption":"Uplay America"},"image":{"@id":"https:\/\/www.uplayamerica.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UPlayAmerica","https:\/\/www.instagram.com\/uplayamerica","https:\/\/www.youtube.com\/@uplayamericaboxermachines"]}]}},"_links":{"self":[{"href":"https:\/\/www.uplayamerica.com\/es\/wp-json\/wp\/v2\/product\/7620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uplayamerica.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.uplayamerica.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uplayamerica.com\/es\/wp-json\/wp\/v2\/media\/9901"}],"wp:attachment":[{"href":"https:\/\/www.uplayamerica.com\/es\/wp-json\/wp\/v2\/media?parent=7620"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.uplayamerica.com\/es\/wp-json\/wp\/v2\/product_brand?post=7620"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.uplayamerica.com\/es\/wp-json\/wp\/v2\/product_cat?post=7620"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.uplayamerica.com\/es\/wp-json\/wp\/v2\/product_tag?post=7620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}